{"id":1203,"date":"2014-12-17T08:59:27","date_gmt":"2014-12-17T07:59:27","guid":{"rendered":"http:\/\/www.satt.fr\/?p=1203"},"modified":"2017-11-13T16:55:17","modified_gmt":"2017-11-13T15:55:17","slug":"ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique","status":"publish","type":"post","link":"https:\/\/www.satt.fr\/en\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/","title":{"rendered":"Ouest Valorisation &#038; le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique"},"content":{"rendered":"<p>La <strong>SATT Ouest Valorisation<\/strong> &amp; le <strong>CNRS<\/strong> ont sign\u00e9 ce mardi 16 d\u00e9cembre un accord-cadre permettant d&#8217;assurer la d\u00e9tection, la protection, la maturation et la commercialisation des r\u00e9sultats de recherche des unit\u00e9s mixtes de recherche en r\u00e9gions Bretagne et Pays de la Loire.<\/p>\n<p>La signature de l&#8217;accord-cadre avec le CNRS permet \u00e0 la SATT Ouest Valorisation d&#8217;investir dans des projets de maturation afin d&#8217;\u00e9tablir la preuve de concept des inventions issues des laboratoires CNRS. Cette d\u00e9marche a pour objectif d\u2019accroitre les opportunit\u00e9s de transfert de technologies issues des laboratoires r\u00e9gionaux vers le monde socio-\u00e9conomique, source d\u2019avantage concurrentiel pour les entreprises. Celles-ci pourront ainsi b\u00e9n\u00e9ficier du potentiel d\u2019investissement et de l\u2019expertise de la SATT Ouest Valorisation.<\/p>\n<p><a href=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2014\/12\/OV_SignatureCNRS_161214.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1206 aligncenter\" src=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2014\/12\/OV_SignatureCNRS_161214-300x199.jpg\" alt=\"OV_SignatureCNRS_161214\" width=\"300\" height=\"199\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.ouest-valorisation.fr\/portfolio\/la-satt-ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/\">\u203a D\u00e9couvrez le communiqu\u00e9 de presse sur le site de Ouest Valorisation.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La SATT Ouest Valorisation &amp; le CNRS ont sign\u00e9 ce mardi 16 d\u00e9cembre un accord-cadre permettant d&#8217;assurer la d\u00e9tection, la protection, la maturation et la commercialisation des r\u00e9sultats de recherche des unit\u00e9s mixtes de recherche en r\u00e9gions Bretagne et Pays de la Loire. La signature de l&#8217;accord-cadre avec le CNRS permet \u00e0 la SATT Ouest [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[535],"tags":[],"class_list":["post-1203","post","type-post","status-publish","format-standard","hentry","category-reussites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ouest Valorisation &amp; le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique - R\u00e9seau SATT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"redacteur SATT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/\"},\"author\":{\"name\":\"redacteur SATT\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/a6836c00a1284a8188e1a05deb2a5e5c\"},\"headline\":\"Ouest Valorisation &#038; le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique\",\"datePublished\":\"2014-12-17T07:59:27+00:00\",\"dateModified\":\"2017-11-13T15:55:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/\"},\"wordCount\":160,\"image\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/OV_SignatureCNRS_161214-300x199.jpg\",\"articleSection\":[\"R\u00e9ussites\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/\",\"name\":\"Ouest Valorisation & le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique - R\u00e9seau SATT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/OV_SignatureCNRS_161214-300x199.jpg\",\"datePublished\":\"2014-12-17T07:59:27+00:00\",\"dateModified\":\"2017-11-13T15:55:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/a6836c00a1284a8188e1a05deb2a5e5c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/OV_SignatureCNRS_161214-300x199.jpg\",\"contentUrl\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/OV_SignatureCNRS_161214-300x199.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ouest Valorisation &#038; le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/\",\"name\":\"R\u00e9seau SATT\",\"description\":\"Les Soci\u00e9t\u00e9s d&#039;Acc\u00e9l\u00e9ration du Transfert de Technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/a6836c00a1284a8188e1a05deb2a5e5c\",\"name\":\"redacteur SATT\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/author\\\/redacteur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ouest Valorisation & le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique - R\u00e9seau SATT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/","twitter_misc":{"Written by":"redacteur SATT","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/#article","isPartOf":{"@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/"},"author":{"name":"redacteur SATT","@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/a6836c00a1284a8188e1a05deb2a5e5c"},"headline":"Ouest Valorisation &#038; le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique","datePublished":"2014-12-17T07:59:27+00:00","dateModified":"2017-11-13T15:55:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/"},"wordCount":160,"image":{"@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.satt.fr\/wp-content\/uploads\/2014\/12\/OV_SignatureCNRS_161214-300x199.jpg","articleSection":["R\u00e9ussites"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/","url":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/","name":"Ouest Valorisation & le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique - R\u00e9seau SATT","isPartOf":{"@id":"https:\/\/www.satt.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/#primaryimage"},"image":{"@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.satt.fr\/wp-content\/uploads\/2014\/12\/OV_SignatureCNRS_161214-300x199.jpg","datePublished":"2014-12-17T07:59:27+00:00","dateModified":"2017-11-13T15:55:17+00:00","author":{"@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/a6836c00a1284a8188e1a05deb2a5e5c"},"breadcrumb":{"@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/#primaryimage","url":"https:\/\/www.satt.fr\/wp-content\/uploads\/2014\/12\/OV_SignatureCNRS_161214-300x199.jpg","contentUrl":"https:\/\/www.satt.fr\/wp-content\/uploads\/2014\/12\/OV_SignatureCNRS_161214-300x199.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.satt.fr\/ouest-valorisation-le-cnrs-collaborent-pour-une-meilleure-valorisation-des-resultats-de-la-recherche-publique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.satt.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Ouest Valorisation &#038; le CNRS collaborent pour une meilleure valorisation des r\u00e9sultats de la recherche publique"}]},{"@type":"WebSite","@id":"https:\/\/www.satt.fr\/en\/#website","url":"https:\/\/www.satt.fr\/en\/","name":"R\u00e9seau SATT","description":"Les Soci\u00e9t\u00e9s d&#039;Acc\u00e9l\u00e9ration du Transfert de Technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.satt.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/a6836c00a1284a8188e1a05deb2a5e5c","name":"redacteur SATT","url":"https:\/\/www.satt.fr\/en\/author\/redacteur\/"}]}},"_links":{"self":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/1203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/comments?post=1203"}],"version-history":[{"count":1,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/1203\/revisions"}],"predecessor-version":[{"id":4826,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/1203\/revisions\/4826"}],"wp:attachment":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/media?parent=1203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/categories?post=1203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/tags?post=1203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}