{"id":1337,"date":"2015-02-06T14:03:44","date_gmt":"2015-02-06T13:03:44","guid":{"rendered":"http:\/\/www.satt.fr\/?p=1337"},"modified":"2017-11-13T16:55:36","modified_gmt":"2017-11-13T15:55:36","slug":"biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015","status":"publish","type":"post","link":"https:\/\/www.satt.fr\/en\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/","title":{"rendered":"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015"},"content":{"rendered":"<p><strong>La SATT Conectus Alsace et Alsace BioValley s&#8217;associent \u00e0 deux partenaires lillois, Eurasant\u00e9* et le p\u00f4le de comp\u00e9titivit\u00e9 NSL**, pour co-organiser \u00e0 Strasbourg la 4e \u00e9dition de BioFIT, la grande Convention d&#8217;affaires internationale des Sciences de la Vie . <\/strong> Profitez des nombreuses opportunit\u00e9s propos\u00e9es lors de cet \u00e9picentre europ\u00e9en de l\u2019open innovation et du transfert de technologies :<\/p>\n<ul>\n<li><span style=\"font-size: 14px;\">un partnering, rendez-vous d\u2019affaires en face \u00e0 face<\/span><\/li>\n<li><span style=\"font-size: 14px;\">des conf\u00e9rences sp\u00e9cialis\u00e9es<\/span><\/li>\n<li><span style=\"font-size: 14px;\">des espaces d&#8217;exposition<\/span><\/li>\n<li><span style=\"font-size: 14px;\">des pr\u00e9sentations d&#8217;opportunit\u00e9s de licensing<\/span><\/li>\n<li><span style=\"font-size: 14px;\">une grande soir\u00e9e Networking<\/span><\/li>\n<\/ul>\n<p>Avec plus de 1 100 participants pr\u00e9sents, dont 50% d&#8217;internationaux issus de 25 pays (Japon, Pays-Bas, Royaume Uni&#8230;), BioFIT est une plateforme incontournable de rencontres et de partenariats entre acad\u00e9miques et industriels de la fili\u00e8re Sant\u00e9. <a href=\"https:\/\/www.biofit-event.com\/biofit-2015\/\" target=\"_blank\" rel=\"noopener\">D\u00e9couvrez BioFIT<\/a> \u00a0 <span style=\"font-size: 12px;\">*Eurasant\u00e9 : Agence de d\u00e9veloppement \u00e9conomique des activit\u00e9s de sant\u00e9 biologie nutrition en r\u00e9gion NPDC <\/span> <span style=\"font-size: 12px;\">**NSL : p\u00f4le de comp\u00e9titivit\u00e9 Nutrition Sant\u00e9 Long\u00e9vit\u00e9<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La SATT Conectus Alsace et Alsace BioValley s&#8217;associent \u00e0 deux partenaires lillois, Eurasant\u00e9* et le p\u00f4le de comp\u00e9titivit\u00e9 NSL**, pour co-organiser \u00e0 Strasbourg la 4e \u00e9dition de BioFIT, la grande Convention d&#8217;affaires internationale des Sciences de la Vie . Profitez des nombreuses opportunit\u00e9s propos\u00e9es lors de cet \u00e9picentre europ\u00e9en de l\u2019open innovation et du transfert [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[538],"tags":[],"class_list":["post-1337","post","type-post","status-publish","format-standard","hentry","category-evenement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015 - R\u00e9seau SATT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"redacteur SATT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/\"},\"author\":{\"name\":\"redacteur SATT\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/a6836c00a1284a8188e1a05deb2a5e5c\"},\"headline\":\"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015\",\"datePublished\":\"2015-02-06T13:03:44+00:00\",\"dateModified\":\"2017-11-13T15:55:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/\"},\"wordCount\":167,\"articleSection\":[\"Ev\u00e9nements\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/\",\"name\":\"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015 - R\u00e9seau SATT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#website\"},\"datePublished\":\"2015-02-06T13:03:44+00:00\",\"dateModified\":\"2017-11-13T15:55:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/a6836c00a1284a8188e1a05deb2a5e5c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/\",\"name\":\"R\u00e9seau SATT\",\"description\":\"Les Soci\u00e9t\u00e9s d&#039;Acc\u00e9l\u00e9ration du Transfert de Technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/a6836c00a1284a8188e1a05deb2a5e5c\",\"name\":\"redacteur SATT\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/author\\\/redacteur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015 - R\u00e9seau SATT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/","twitter_misc":{"Written by":"redacteur SATT","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/#article","isPartOf":{"@id":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/"},"author":{"name":"redacteur SATT","@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/a6836c00a1284a8188e1a05deb2a5e5c"},"headline":"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015","datePublished":"2015-02-06T13:03:44+00:00","dateModified":"2017-11-13T15:55:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/"},"wordCount":167,"articleSection":["Ev\u00e9nements"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/","url":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/","name":"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015 - R\u00e9seau SATT","isPartOf":{"@id":"https:\/\/www.satt.fr\/en\/#website"},"datePublished":"2015-02-06T13:03:44+00:00","dateModified":"2017-11-13T15:55:36+00:00","author":{"@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/a6836c00a1284a8188e1a05deb2a5e5c"},"breadcrumb":{"@id":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.satt.fr\/biofit-se-tiendra-a-strasbourg-2015-les-1-et-2-decembre-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.satt.fr\/en\/"},{"@type":"ListItem","position":2,"name":"BioFIT se tiendra \u00e0 Strasbourg 2015 les 1 et 2 d\u00e9cembre 2015"}]},{"@type":"WebSite","@id":"https:\/\/www.satt.fr\/en\/#website","url":"https:\/\/www.satt.fr\/en\/","name":"R\u00e9seau SATT","description":"Les Soci\u00e9t\u00e9s d&#039;Acc\u00e9l\u00e9ration du Transfert de Technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.satt.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/a6836c00a1284a8188e1a05deb2a5e5c","name":"redacteur SATT","url":"https:\/\/www.satt.fr\/en\/author\/redacteur\/"}]}},"_links":{"self":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/1337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/comments?post=1337"}],"version-history":[{"count":1,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/1337\/revisions"}],"predecessor-version":[{"id":4814,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/1337\/revisions\/4814"}],"wp:attachment":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/media?parent=1337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/categories?post=1337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/tags?post=1337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}