{"id":27115,"date":"2021-09-27T16:02:16","date_gmt":"2021-09-27T14:02:16","guid":{"rendered":"https:\/\/www.satt.fr\/satt-up-septembre-2021\/"},"modified":"2021-09-27T16:02:16","modified_gmt":"2021-09-27T14:02:16","slug":"satt-up-septembre-2021","status":"publish","type":"post","link":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/","title":{"rendered":"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021"},"content":{"rendered":"<div id=\"pl-27115\"  class=\"panel-layout\" ><div id=\"pg-27115-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-27115-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Retrouvez les derni\u00e8res actualit\u00e9s des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #SATTUP.<\/strong><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-27115-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-27115-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>TreeFrog Therapeutics l\u00e8ve 64 millions d\u2019euros avec le soutien de Bpifrance et d\u2019investisseurs internationaux.<\/strong><em> (Aquitaine Science Transfert)<\/em><\/p>\n<p>TreeFrog Therapeutics, sp\u00e9cialiste des th\u00e9rapies cellulaires issues de cellules souches, annonce aujourd\u2019hui avoir r\u00e9alis\u00e9 une lev\u00e9e de fonds de 64 millions d\u2019euros dans le cadre d\u2019une S\u00e9rie B, deux ans apr\u00e8s un premier tour de table de 6,5 millions d\u2019euros. Ce tour B servira \u00e0 financer le d\u00e9ploiement de la technologie C-StemTM, \u00e0 implanter TreeFrog Therapeutics aux Etats-Unis et au Japon, et \u00e0 \u00e9tendre son portefeuille de th\u00e9rapies cellulaires avec l\u2019objectif de lancer les premiers essais cliniques d\u00e8s 2024.<\/p>\n<p><a href=\"https:\/\/treefrog.fr\/\">treefrog.fr<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-27115-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-1-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"2\" ><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"35\" src=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-150x35.png\" class=\"image wp-image-26905  attachment-thumbnail size-thumbnail\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-150x35.png 150w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-300x69.png 300w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-1024x236.png 1024w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-768x177.png 768w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-500x115.png 500w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-600x138.png 600w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1-200x46.png 200w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/TreeFrog-Therapeutics-logo-1.png 1029w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><\/div><\/div><div id=\"pg-27115-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-27115-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Cr\u00e9ation d\u2019AbilyCare, start-up innovante pour une m\u00e9decine pr\u00e9ventive, pr\u00e9dictive et personnalis\u00e9e \u00e0 tout \u00e2ge. <\/strong><em>(Erganeo)<\/em><\/p>\n<p>Pour r\u00e9pondre aux probl\u00e9matiques de suivi et de pr\u00e9vention en sant\u00e9, AbilyCare propose un dispositif m\u00e9dical simple de quantification et de suivi des deux principaux indicateurs de la motricit\u00e9 : la marche et l\u2019\u00e9quilibre. Issue de la recherche acad\u00e9mique, et d\u00e9velopp\u00e9e au sein du groupe Engie pendant plusieurs ann\u00e9es, la soci\u00e9t\u00e9 AbilyCare a \u00e9t\u00e9 lanc\u00e9e le 10 juillet 2021 avec l\u2019appui et le soutien d\u2019Erganeo. La start-up francilienne vise le secteur de la pr\u00e9vention et de la r\u00e9adaptation. Elle propose aux professionnels de sant\u00e9 et aux acteurs sociaux une solution num\u00e9rique de quantification de la motricit\u00e9 permettant notamment d\u2019\u00e9valuer les risques de fragilit\u00e9.<\/p>\n<p><a href=\"https:\/\/www.abilycare.com\/\">www.abilycare.com<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-27115-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-2-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"4\" ><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"27\" src=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-150x27.png\" class=\"image wp-image-26907  attachment-thumbnail size-thumbnail\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-150x27.png 150w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-300x54.png 300w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-1024x185.png 1024w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-768x139.png 768w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-500x90.png 500w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-600x108.png 600w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN-200x36.png 200w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo-AbilyCare-CMJN.png 1286w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><\/div><\/div><div id=\"pg-27115-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-27115-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-3-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Pulsalys passe le cap de la 100\u00e8me startup cr\u00e9\u00e9e et pr\u00e9senter sa nouvelle p\u00e9pite : Muodim, au-d\u00e9l\u00e0 du visible. <\/strong><em>(PULSALYS)<\/em><\/p>\n<p>PULSALYS, l\u2019incubateur et acc\u00e9l\u00e9rateur Deep Tech de Lyon et Saint-Etienne, vient de franchir la barre symbolique des 100 startups cr\u00e9\u00e9es. Ce cap franchi et les r\u00e9sultats de ses startups illustrent le r\u00f4le majeur que PULSALYS joue sur l\u2019attractivit\u00e9 et l\u2019impact socio-\u00e9conomique de la R\u00e9gion Auvergne-Rh\u00f4ne-Alpes, qui la soutient, ,mais aussi plus largement sur la relance \u00e9conomique fran\u00e7aise. En t\u00e9moigne, la startup Muodim, cr\u00e9\u00e9e cet \u00e9t\u00e9, qui oeuvre d\u00e9j\u00e0 dans la construction des nouvelles lignes de m\u00e9tro du Grand Paris pour les Jeux Olympiques 2024.<\/p>\n<p><a href=\"https:\/\/www.muonsight.eu\/\">www.muonsight.eu<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-27115-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-3-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"6\" ><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo_muodim_couleur-150x150.png\" class=\"image wp-image-26909  attachment-thumbnail size-thumbnail\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo_muodim_couleur-150x150.png 150w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo_muodim_couleur-300x300.png 300w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo_muodim_couleur-100x100.png 100w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/logo_muodim_couleur.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><\/div><\/div><div id=\"pg-27115-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-27115-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-4-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Moovency lance KIMEA Cloud pour simplifier la pr\u00e9vention des troubles musculosquelettiques en secteur industriel. <\/strong><em>(Ouest Valorisation)<\/em><\/p>\n<p>Parce que personne ne devrait avoir \u00e0 choisir entre son travail et sa sant\u00e9, la start-up bretonne Moovency propose depuis 2018 des solutions innovantes pour lutter contre les troubles musculosquelettiques en secteur industriel. Le 28 septembre, elle d\u00e9voilera sa toute nouvelle solution pens\u00e9e par et pour des ergonomes : KIMEA Cloud, une plateforme web accompagn\u00e9e d\u2019une application mobile.<\/p>\n<p><a href=\"https:\/\/moovency.com\/\">moovency.com<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-27115-4-1\"  class=\"panel-grid-cell\" ><div id=\"panel-27115-4-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"8\" ><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/Logo-Moovency-1-150x150.jpg\" class=\"image wp-image-26916  attachment-thumbnail size-thumbnail\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/Logo-Moovency-1-150x150.jpg 150w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/Logo-Moovency-1-100x100.jpg 100w, https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/09\/Logo-Moovency-1.jpg 200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Retrouvez les derni\u00e8res actualit\u00e9s des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #SATTUP. TreeFrog Therapeutics l\u00e8ve 64 millions d\u2019euros avec le soutien de Bpifrance et d\u2019investisseurs internationaux. (Aquitaine Science Transfert) TreeFrog Therapeutics, sp\u00e9cialiste des th\u00e9rapies cellulaires issues de cellules souches, annonce aujourd\u2019hui avoir r\u00e9alis\u00e9 une lev\u00e9e de fonds de 64 millions d\u2019euros dans le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25224,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[567,604],"tags":[],"class_list":["post-27115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en","category-startup-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021 - R\u00e9seau SATT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/6f20a7d0bc03146f6e34a9f08d941fec\"},\"headline\":\"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021\",\"datePublished\":\"2021-09-27T14:02:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/\"},\"wordCount\":518,\"image\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sattup2.jpg\",\"articleSection\":[\"News\",\"Start-up\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/\",\"name\":\"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021 - R\u00e9seau SATT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sattup2.jpg\",\"datePublished\":\"2021-09-27T14:02:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/6f20a7d0bc03146f6e34a9f08d941fec\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sattup2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.satt.fr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sattup2.jpg\",\"width\":2560,\"height\":1428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/satt-up-septembre-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/\",\"name\":\"R\u00e9seau SATT\",\"description\":\"Les Soci\u00e9t\u00e9s d&#039;Acc\u00e9l\u00e9ration du Transfert de Technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/#\\\/schema\\\/person\\\/6f20a7d0bc03146f6e34a9f08d941fec\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/www.satt.fr\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021 - R\u00e9seau SATT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/#article","isPartOf":{"@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/"},"author":{"name":"admin","@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/6f20a7d0bc03146f6e34a9f08d941fec"},"headline":"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021","datePublished":"2021-09-27T14:02:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/"},"wordCount":518,"image":{"@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/05\/sattup2.jpg","articleSection":["News","Start-up"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/","url":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/","name":"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021 - R\u00e9seau SATT","isPartOf":{"@id":"https:\/\/www.satt.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/05\/sattup2.jpg","datePublished":"2021-09-27T14:02:16+00:00","author":{"@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/6f20a7d0bc03146f6e34a9f08d941fec"},"breadcrumb":{"@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/#primaryimage","url":"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/05\/sattup2.jpg","contentUrl":"https:\/\/www.satt.fr\/wp-content\/uploads\/2021\/05\/sattup2.jpg","width":2560,"height":1428},{"@type":"BreadcrumbList","@id":"https:\/\/www.satt.fr\/en\/satt-up-septembre-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.satt.fr\/en\/"},{"@type":"ListItem","position":2,"name":"SATT-UP ! L\u2019actualit\u00e9 des start-up accompagn\u00e9es par les membres du R\u00e9seau SATT #27 \u2013 Septembre 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.satt.fr\/en\/#website","url":"https:\/\/www.satt.fr\/en\/","name":"R\u00e9seau SATT","description":"Les Soci\u00e9t\u00e9s d&#039;Acc\u00e9l\u00e9ration du Transfert de Technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.satt.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.satt.fr\/en\/#\/schema\/person\/6f20a7d0bc03146f6e34a9f08d941fec","name":"admin","url":"https:\/\/www.satt.fr\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/27115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/comments?post=27115"}],"version-history":[{"count":0,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/posts\/27115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/media\/25224"}],"wp:attachment":[{"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/media?parent=27115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/categories?post=27115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.satt.fr\/en\/wp-json\/wp\/v2\/tags?post=27115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}